{"id":1182,"date":"2020-10-08T07:57:40","date_gmt":"2020-10-08T05:57:40","guid":{"rendered":"https:\/\/dupraz-snow.com\/?page_id=1182"},"modified":"2020-12-08T16:55:59","modified_gmt":"2020-12-08T15:55:59","slug":"snowboard-product-chooser","status":"publish","type":"page","link":"https:\/\/dupraz-snow.com\/en\/snowboard-product-chooser\/","title":{"rendered":"Snowboard selection advice"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-1182\" data-postid=\"1182\" class=\"themify_builder_content themify_builder_content-1182 themify_builder tf_clear\">\n                    <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_y39l954 tb_first tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_96do954 first\">\n                    <!-- module image -->\n<div  class=\"module module-image tb_uitj354 image-top   auto_fullwidth tf_mw\" data-lazy=\"1\">\n        <div class=\"image-wrap tf_rel tf_mw\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/DUPRAZ_D1-original-range-1.jpg\" class=\"wp-post-image wp-image-1200\" title=\"DUPRAZ_D1-original range-1\" alt=\"Dupraz Snowboard\" srcset=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/DUPRAZ_D1-original-range-1.jpg 1024w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/DUPRAZ_D1-original-range-1-300x225.jpg 300w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/DUPRAZ_D1-original-range-1-600x450.jpg 600w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/DUPRAZ_D1-original-range-1-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\">    \n        <\/div>\n    <!-- \/image-wrap -->\n    \n        <\/div>\n<!-- \/module image -->        <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_56tu658 tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_6s8z658 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_jv8r165    wow\" data-tf-animation=\"fadeInUp\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h1 align=\"left\">Choisir sa board<\/h1>\n<div align=\"left\">\n<p>Vous h\u00e9sitez entre plusieurs mod\u00e8les ? Contactez nous directement.\u00a0<\/p>\n<p>Afin de pouvoir vous renseigner de mani\u00e8re personnalis\u00e9e et vous conseiller ainsi sur le produit le plus adapt\u00e9 \u00e0 votre gabarit, exp\u00e9rience et style de ride, veuillez SVP remplir le formulaire ci-dessous.<\/p>\n<div align=\"left\">\n<p>Nous vous r\u00e9pondrons aussi vite que possible.<\/p>\n<\/div>\n<div align=\"left\"><strong>Le staff Dupraz Snow<br \/><br \/><br \/><\/strong><\/div>\n<div align=\"left\">Avant de remplir le formulaire, vous pouvez lire les conseils ci-dessous&#8230;<\/div>\n<\/div>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_else209 tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_qny8209 first\">\n                    <!-- module accordion -->\n<div  class=\"module module-accordion tb_8s5a131  wow\" data-behavior=\"toggle\" data-tf-animation=\"fadeInUp\" data-tf-animation_delay=\"0.4\" data-lazy=\"1\">\n    \n    <ul class=\"ui module-accordion   tb_default_color\">\n            <li>\n            <div class=\"accordion-title tf_rel\">\n                <a href=\"#acc-8s5a131-0\" class=\"tb_title_accordion\" aria-controls=\"acc-8s5a131-0\" aria-expanded=\"false\">\n                    <i class=\"accordion-icon\"><svg  class=\"tf_fa tf-ti-plus\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" aria-hidden=\"true\"><use href=\"#tf-ti-plus\" xlink:href=\"#tf-ti-plus\"><\/use><\/svg><\/i>                    <i class=\"accordion-active-icon tf_hide\"><svg  class=\"tf_fa tf-ti-minus\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" aria-hidden=\"true\"><use href=\"#tf-ti-minus\" xlink:href=\"#tf-ti-minus\"><\/use><\/svg><\/i>                    <span class=\"accordion-title-wrap\">Conseils pour choisir la bonne board<\/span>                <\/a>\n            <\/div><!-- .accordion-title -->\n            <div id=\"acc-8s5a131-0\" data-id=\"acc-8s5a131-0\" aria-hidden=\"true\" class=\"accordion-content tf_hide tf_clearfix\">\n                                    <div class=\"tb_text_wrap\">\n                        <div align=\"left\"><strong>Choisir la bonne taille<\/strong><\/div>\n<div>\u00a0<\/div>\n<div align=\"left\">\n<p>Notre shape a \u00e9t\u00e9 maintes fois reconnu par les tests magazines et par tous ceux qui ont essay\u00e9, comme le plus polyvalent qui soit sur le march\u00e9. Nous avons simplement d\u00e9clin\u00e9 ce concept en tailles et flex diff\u00e9rents, ce qui couvre la grande majorit\u00e9 des riders. Ce choix de diff\u00e9rentes rigidit\u00e9s de la D1 permet de se rapprocher au plus pr\u00e8s d&#8217;une conception personnalis\u00e9e, de ce qu&#8217;on pourrait appeler du &#8220;sur-mesure&#8221;.<\/p>\n<p>1 &#8211; Board de votre taille : programme all mountain classique.<br \/>2 &#8211; Une taille en-dessous : programme all mountain ludique avec board plus joueuse, plus maniable.<br \/>3 &#8211; Une taille au-dessus : programme all mountain avec grosse option freeride.<\/p>\n<\/div>\n<div><a href=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/choix_tailles.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1195\" src=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/choix_tailles.jpg\" alt=\"Dupraz Snowboard\" width=\"409\" height=\"373\" srcset=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/choix_tailles.jpg 409w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/choix_tailles-300x274.jpg 300w\" sizes=\"auto, (max-width: 409px) 100vw, 409px\"><\/a><\/div>\n<div align=\"left\"><strong>Exemple avec un rider de 1m80 :<\/strong><\/div>\n<div align=\"left\">&#8211; Prendra un 6&#8242; (1m78) pour un programme freeride.<\/div>\n<div align=\"left\">&#8211; Prendra une 6&#8217;3&#8243; (193cm) pour un usage hors piste et grosse poudre.<\/div>\n<div align=\"left\">&#8211; Prendra une 5&#8217;5&#8243; (165 cm) pour un usage plus joueur, plus polyvalent.<\/div>\n<div align=\"left\">&#8211; Prendra une 5&#8217;2&#8243; (158 cm) pour un usage shred \/ fish.<\/div>\n<div>\u00a0<\/div>\n<div align=\"left\"><strong>Exemple avec une rideuse qui mesure 1m62 :<\/strong><\/div>\n<div align=\"left\">&#8211; Si elle prend la taille juste au-dessus d&#8217;elle, soit une 5&#8217;5&#8243; (1m65) son programme sera\u00a0r\u00e9solument freeride.<\/div>\n<div align=\"left\">&#8211; Avec une 5&#8217;2&#8243; (1m58) elle sera toujours \u00e0 l&#8217;aise en poudre mais va beaucoup gagner en\u00a0maniabilit\u00e9 sur piste.<\/div>\n<div align=\"left\">\u00a0<\/div>\n<div align=\"left\">\n<div class=\"wa-comp wa-text wa-bg-gradient param[grad(rgba(0,0,0,0)) border(0 #969696)] \">\n<div align=\"left\"><strong>Comparaisons avec d&#8217;autres shapes<\/strong><\/div>\n<div>\u00a0Nos shapes ont cette particularit\u00e9 d&#8217;avoir une tr\u00e8s faible longueur de carre par rapport \u00e0 la longueur totale de la board. Les avantages sont une plus grande maniabilit\u00e9 alli\u00e9e \u00e0 une portance importante, qui vous permettra de flotter les jours de poudreuse. En effet notre longue spatule n&#8217;entrave en rien les capacit\u00e9s de ride sur piste, par contre en poudreuse elle offre des acc\u00e9l\u00e9rations et une flottaison meilleurs que n&#8217;importe quel autre shape du march\u00e9.<\/div>\n<\/div>\n<div class=\"wa-comp wa-text wa-bg-gradient param[grad(rgba(0,0,0,0)) border(0 #969696)] \">\n<div>\n<div align=\"center\">\u00a0<\/div>\n<\/div>\n<\/div>\n<div class=\"wa-comp wa-text wa-bg-gradient param[grad(rgba(0,0,0,0)) border(0 #969696)] \">\n<div align=\"left\">&#8211; Nos 5&#8217;2&#8243; qui mesurent 158cm sont aussi habiles et joueuses sur piste d&#8217;une board de 152 au shape classique. En poudreuse par contre les 5&#8217;2&#8243; laissent les boards\u00a0 de 160 cm\u00a0 loin derri\u00e8re et vous ridez sur les deux pieds, \u00e9quilibr\u00e9, sans soucis pour d\u00e9jauger et sans vous fatiguer les cuisses !<\/div>\n<div>\u00a0&#8211; Sur le m\u00eame principe, nos 5&#8217;5&#8243; qui font 165cm sont aussi maniables que des boards au shape classique de 157 cm.<\/div>\n<div>\u00a0&#8211; Les 6&#8242; (178cm) \u00e9quivalent \u00e0 des 164, alors que notre plus grande 6&#8217;3&#8243; se ride comme une 172.<\/div>\n<div>\u00a0<\/div>\n<div align=\"left\">Voici un petit dessin qui r\u00e9sume ces diff\u00e9rences.<br \/><a href=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/dupraz-size-chart-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1373\" src=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/dupraz-size-chart-1.jpg\" alt=\"Dupraz Snowboard\" width=\"520\" height=\"362\" srcset=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/dupraz-size-chart-1.jpg 1362w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/dupraz-size-chart-1-300x209.jpg 300w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/dupraz-size-chart-1-600x419.jpg 600w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/dupraz-size-chart-1-1024x714.jpg 1024w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/dupraz-size-chart-1-768x536.jpg 768w\" sizes=\"auto, (max-width: 520px) 100vw, 520px\"><\/a><\/div>\n<div>\u00a0<\/div>\n<\/div>\n<\/div>\n<div align=\"left\"><strong>Vous avez encore un doute ?<\/strong> Demandez quelle taille de board vous irait le mieux en remplissant le formulaire ci-dessous.<br \/>Nous r\u00e9pondons vite et\u00a0pr\u00e9cis\u00e9ment \u00e0 toutes vos questions.<\/div>                    <\/div>\n                            <\/div><!-- .accordion-content -->\n        <\/li>\n            <li>\n            <div class=\"accordion-title tf_rel\">\n                <a href=\"#acc-8s5a131-1\" class=\"tb_title_accordion\" aria-controls=\"acc-8s5a131-1\" aria-expanded=\"false\">\n                    <i class=\"accordion-icon\"><svg  class=\"tf_fa tf-ti-plus\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" aria-hidden=\"true\"><use href=\"#tf-ti-plus\" xlink:href=\"#tf-ti-plus\"><\/use><\/svg><\/i>                    <i class=\"accordion-active-icon tf_hide\"><svg  class=\"tf_fa tf-ti-minus\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" aria-hidden=\"true\"><use href=\"#tf-ti-minus\" xlink:href=\"#tf-ti-minus\"><\/use><\/svg><\/i>                    <span class=\"accordion-title-wrap\">Choisir le bon flex<\/span>                <\/a>\n            <\/div><!-- .accordion-title -->\n            <div id=\"acc-8s5a131-1\" data-id=\"acc-8s5a131-1\" aria-hidden=\"true\" class=\"accordion-content tf_hide tf_clearfix\">\n                                    <div class=\"tb_text_wrap\">\n                        <div align=\"left\"><strong>Choisir le bon flex<\/strong><\/div>\n<div>\u00a0<\/div>\n<div align=\"left\">Nos gamme est compos\u00e9e de mod\u00e8les class\u00e9s d&#8217;abord par tailles, puis sur certains mod\u00e8les par flex, afin d&#8217;\u00eatre au plus pr\u00e8s d&#8217;une board custom, parfaitement adapt\u00e9e \u00e0 votre style de ride et gabarit.<\/div>\n<div>\u00a0<\/div>\n<div align=\"left\">Nos flex sont nomm\u00e9s de la fa\u00e7on suivante : &#8220;PLAY&#8221; (pour standard), &#8220;FULL +&#8221; pour un flex interm\u00e9diaire et enfin &#8220;POWER ++&#8221; pour un flex rigide.<\/div>\n<div>\u00a0<\/div>\n<div align=\"left\">Plus la board est rigide,\u00a0 plus elle est adapt\u00e9e \u00e0 un gabarit lourd, ou alors \u00e0 quelqu&#8217;un qui ride avec des appuis puissants.<\/div>\n<div align=\"left\">A l&#8217;inverse une board souple est plus adapt\u00e9e \u00e0 quelqu&#8217;un de l\u00e9ger ou un rider (ou rideuse) qui surfe plus en toucher de neige.<\/div>\n<div>\u00a0<\/div>\n<div align=\"left\">&#8211; Les mod\u00e8les 5&#8217;2&#8243; sont en flex PLAY.<\/div>\n<div align=\"left\">&#8211; Les 5&#8217;5&#8243; existent dans les 3 versions de flex.<\/div>\n<div align=\"left\">&#8211; La 6&#8242; en deux duret\u00e9s (+ et ++)<\/div>\n<div align=\"left\">&#8211; Les X\u00a0 sont particuli\u00e8res, car elles restent flexibles, mais avec une nervosit\u00e9 accrue. Leur flex reste cependant assez comparable \u00e0 une board de type +.<\/div>\n<div align=\"left\">&#8211; Les Split ont un flex \u00e0 peine plus r\u00e9dige d&#8217;un flex PLAY.<\/div>\n<div align=\"left\">\u00a0<\/div>\n<div align=\"left\">&#8211; La 6&#8217;3&#8243; est un mod\u00e8le engag\u00e9, dont le flex est assez ferme. Mais sur toute la longueur cette board se d\u00e9forme bien malgr\u00e9 tout. Son flex est un &#8220;POWER ++&#8221;.<\/div>\n<div>\u00a0<\/div>\n<div align=\"left\"><strong>Vous avez un doute ?<\/strong> Demandez nous quel flex vous irait le mieux.<\/div>                    <\/div>\n                            <\/div><!-- .accordion-content -->\n        <\/li>\n        <\/ul>\n\n<\/div><!-- \/module accordion --><!-- module text -->\n<div  class=\"module module-text tb_m49n209    wow\" data-tf-animation=\"fadeInUp\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h3>Ces informations vont nous permettre de choisir la meilleure board pour vous<\/h3>\n<h5>R\u00e9ponse personnalis\u00e9e sous 48 heures max.<\/h5>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_lko5974    wow\" data-tf-animation=\"fadeInUp\" data-tf-animation_delay=\"0.4\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-1188\"><form id=\"wpforms-form-1188\" class=\"wpforms-validate wpforms-form\" data-formid=\"1188\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/1182\" data-token=\"c8dc9cb0ec201b48a6b7a003458404c5\" data-token-time=\"1788332080\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-1188-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\">Nom <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-1188-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" required><label for=\"wpforms-1188-field_0\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-1188-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" required><label for=\"wpforms-1188-field_0-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-1188-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_1\">E-mail <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-1188-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"Votre email, pensez \u00e0 bien le v\u00e9rifier...\" spellcheck=\"false\" required><\/div><div id=\"wpforms-1188-field_4-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_4\">Votre pays <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-1188-field_4\" class=\"wpforms-field-medium wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-medium\" data-search-enabled=\"1\" name=\"wpforms[fields][4]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled ><\/option><option value=\"France\"  selected='selected'>France<\/option><option value=\"Suisse\" >Suisse<\/option><option value=\"- - Europe - - \" >- - Europe - -<\/option><option value=\"Allemagne\" >Allemagne<\/option><option value=\"Autriche\" >Autriche<\/option><option value=\"Belgique\" >Belgique<\/option><option value=\"Bulgarie\" >Bulgarie<\/option><option value=\"Chypre\" >Chypre<\/option><option value=\"Croatie\" >Croatie<\/option><option value=\"Danemark\" >Danemark<\/option><option value=\"Espagne\" >Espagne<\/option><option value=\"Estonie\" >Estonie<\/option><option value=\"Finlande\" >Finlande<\/option><option value=\"Gr\u00e8ce\" >Gr\u00e8ce<\/option><option value=\"Hongrie\" >Hongrie<\/option><option value=\"(IE)\" >(IE)<\/option><option value=\"Italie\" >Italie<\/option><option value=\"Lettonie\" >Lettonie<\/option><option value=\"Lituanie\" >Lituanie<\/option><option value=\"Luxembourg\" >Luxembourg<\/option><option value=\"Malte\" >Malte<\/option><option value=\"Pays-Bas\" >Pays-Bas<\/option><option value=\"Pologne\" >Pologne<\/option><option value=\"Portugal\" >Portugal<\/option><option value=\"R\u00e9publique tch\u00e8que\" >R\u00e9publique tch\u00e8que<\/option><option value=\"Roumanie\" >Roumanie<\/option><option value=\"Royaume-Uni\" >Royaume-Uni<\/option><option value=\"Slovaquie\" >Slovaquie<\/option><option value=\"Slov\u00e9nie\" >Slov\u00e9nie<\/option><option value=\"Su\u00e8de\" >Su\u00e8de<\/option><option value=\"- - Reste du monde - - \" >- - Reste du monde - -<\/option><option value=\"Argentine\" >Argentine<\/option><option value=\"Australie\" >Australie<\/option><option value=\"Canada\" >Canada<\/option><option value=\"Chili\" >Chili<\/option><option value=\"Chine\" >Chine<\/option><option value=\"Islande\" >Islande<\/option><option value=\"Japon\" >Japon<\/option><option value=\"Nouvelle-Z\u00e9lande\" >Nouvelle-Z\u00e9lande<\/option><option value=\"Russie\" >Russie<\/option><option value=\"Ukraine\" >Ukraine<\/option><option value=\"USA\" >USA<\/option><option value=\"Autre\" >Autre<\/option><\/select><\/div><div id=\"wpforms-1188-field_30-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"30\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_30\">Votre t\u00e9l\u00e9phone<\/label><input type=\"tel\" id=\"wpforms-1188-field_30\" class=\"wpforms-field-medium wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][30]\" aria-label=\"Votre t\u00e9l\u00e9phone\" ><div class=\"wpforms-field-description\">Dans le cas o\u00f9 Serge Dupraz aurait besoin de vous rappeler pour affiner le conseil.<\/div><\/div><div id=\"wpforms-1188-field_7-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_7\">Vous \u00eates <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-1188-field_7\" class=\"wpforms-field-medium wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-medium\" data-search-enabled=\"\" name=\"wpforms[fields][7]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Une femme\" >Une femme<\/option><option value=\"Un homme\" >Un homme<\/option><\/select><\/div><div id=\"wpforms-1188-field_8-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_8\">Votre \u00e2ge <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-1188-field_8\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][8]\" step=\"any\" required><\/div><div id=\"wpforms-1188-field_26-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"26\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_26\">Votre taille en cm <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-1188-field_26\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][26]\" step=\"any\" required><\/div><div id=\"wpforms-1188-field_27-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"27\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_27\">Votre poids en kg <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-1188-field_27\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][27]\" step=\"any\" required><\/div><div id=\"wpforms-1188-field_29-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"29\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_29\">Votre pointure <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-1188-field_29\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][29]\" step=\"any\" required><\/div><div id=\"wpforms-1188-field_9-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_9\">Votre niveau de ride<\/label><select id=\"wpforms-1188-field_9\" class=\"wpforms-field-medium choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-medium\" data-search-enabled=\"\" name=\"wpforms[fields][9]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>D\u00e9finissez au plus pr\u00e8s votre niveau de pratique<\/option><option value=\"D\u00e9butant en cours d&#039;apprentissage \" >D\u00e9butant en cours d&#039;apprentissage<\/option><option value=\"Interm\u00e9diaire\" >Interm\u00e9diaire<\/option><option value=\"Niveau confirm\u00e9\" >Niveau confirm\u00e9<\/option><option value=\"Niveau expert\" >Niveau expert<\/option><option value=\"Pro rider ou ex pro rider\" >Pro rider ou ex pro rider<\/option><\/select><\/div><div id=\"wpforms-1188-field_10-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"10\"><label class=\"wpforms-field-label\">Plus de pr\u00e9cisions sur votre style de ride <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-1188-field_10\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_10_1\" name=\"wpforms[fields][10][]\" value=\"Tranquille\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_10_1\">Tranquille<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_10_2\" name=\"wpforms[fields][10][]\" value=\"Agressif\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_10_2\">Agressif<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_10_3\" name=\"wpforms[fields][10][]\" value=\"Vari\u00e9\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_10_3\">Vari\u00e9<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_10_5\" name=\"wpforms[fields][10][]\" value=\"Fluide\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_10_5\">Fluide<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_10_6\" name=\"wpforms[fields][10][]\" value=\"Technique\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_10_6\">Technique<\/label><\/li><\/ul><\/div><div id=\"wpforms-1188-field_11-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"11\"><label class=\"wpforms-field-label\">Style de courbes que vous pr\u00e9f\u00e9rez <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-1188-field_11\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_11_1\" name=\"wpforms[fields][11][]\" value=\"Petites\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_11_1\">Petites<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_11_2\" name=\"wpforms[fields][11][]\" value=\"Moyennes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_11_2\">Moyennes<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_11_3\" name=\"wpforms[fields][11][]\" value=\"Grande\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_11_3\">Grande<\/label><\/li><\/ul><\/div><div id=\"wpforms-1188-field_12-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_12\">Temps pass\u00e9 entre la piste et le hors-piste <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-1188-field_12\" class=\"wpforms-field-small wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-small\" data-search-enabled=\"\" name=\"wpforms[fields][12]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Piste 0 % - Hors piste 100%\" >Piste 0 % - Hors piste 100%<\/option><option value=\"Piste 30 % - Hors piste 70%\" >Piste 30 % - Hors piste 70%<\/option><option value=\"Piste 50 % - Hors piste 50%\" >Piste 50 % - Hors piste 50%<\/option><option value=\"Piste 70 % - Hors piste 30%\" >Piste 70 % - Hors piste 30%<\/option><option value=\"Piste 100 % - Hors piste 0%\" >Piste 100 % - Hors piste 0%<\/option><\/select><\/div><div id=\"wpforms-1188-field_13-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"13\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_13\">Depuis combien d&#039;ann\u00e9es ridez-vous ? <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-1188-field_13\" class=\"wpforms-field-small wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-small\" data-search-enabled=\"1\" name=\"wpforms[fields][13]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"1\" >1<\/option><option value=\"2\" >2<\/option><option value=\"3\" >3<\/option><option value=\"4\" >4<\/option><option value=\"5\" >5<\/option><option value=\"6\" >6<\/option><option value=\"7\" >7<\/option><option value=\"8\" >8<\/option><option value=\"9\" >9<\/option><option value=\"10\" >10<\/option><option value=\"11\" >11<\/option><option value=\"12\" >12<\/option><option value=\"13\" >13<\/option><option value=\"14\" >14<\/option><option value=\"15\" >15<\/option><option value=\"16\" >16<\/option><option value=\"17\" >17<\/option><option value=\"18\" >18<\/option><option value=\"19\" >19<\/option><option value=\"20\" >20<\/option><option value=\"21\" >21<\/option><option value=\"22\" >22<\/option><option value=\"23\" >23<\/option><option value=\"24\" >24<\/option><option value=\"25\" >25<\/option><option value=\"26 et plus\" >26 et plus<\/option><\/select><\/div><div id=\"wpforms-1188-field_14-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"14\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_14\">Nombre de sorties \u00e0 la neige (en snowboard et par ann\u00e9e) <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-1188-field_14\" class=\"wpforms-field-small wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-small\" data-search-enabled=\"\" name=\"wpforms[fields][14]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Une semaine ou moins\" >Une semaine ou moins<\/option><option value=\"2 semaines\" >2 semaines<\/option><option value=\"3 semaines\" >3 semaines<\/option><option value=\"4 semaines\" >4 semaines<\/option><option value=\"30 \u00e0 50 jours\" >30 \u00e0 50 jours<\/option><option value=\"50 jours et plus\" >50 jours et plus<\/option><\/select><\/div><div id=\"wpforms-1188-field_20-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"20\"><label class=\"wpforms-field-label\">Taille de board habituelle sur ce programme <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-1188-field_20\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_20_1\" name=\"wpforms[fields][20][]\" value=\"Sans r\u00e9ponse\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_20_1\">Sans r\u00e9ponse<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_20_2\" name=\"wpforms[fields][20][]\" value=\" inf. \u00e0 148 cm\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_20_2\">inf. \u00e0 148 cm<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_20_3\" name=\"wpforms[fields][20][]\" value=\"entre 149 et 153 cm\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_20_3\">entre 149 et 153 cm<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_20_7\" name=\"wpforms[fields][20][]\" value=\"entre 154 et 158 cm\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_20_7\">entre 154 et 158 cm<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_20_6\" name=\"wpforms[fields][20][]\" value=\"entre 159 et 162 cm\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_20_6\">entre 159 et 162 cm<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_20_5\" name=\"wpforms[fields][20][]\" value=\"entre 163 et 166 cm\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_20_5\">entre 163 et 166 cm<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_20_4\" name=\"wpforms[fields][20][]\" value=\"sup. \u00e0 167 cm\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_20_4\">sup. \u00e0 167 cm<\/label><\/li><\/ul><\/div><div id=\"wpforms-1188-field_28-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"28\"><label class=\"wpforms-field-label\">Cochez la ou les diff\u00e9rentes pratiques <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-1188-field_28\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_28_1\" name=\"wpforms[fields][28][]\" value=\"Freestyle park\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_28_1\">Freestyle park<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_28_2\" name=\"wpforms[fields][28][]\" value=\"Freestyle all-mountain\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_28_2\">Freestyle all-mountain<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_28_3\" name=\"wpforms[fields][28][]\" value=\"Petits sauts bords de piste\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_28_3\">Petits sauts bords de piste<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_28_7\" name=\"wpforms[fields][28][]\" value=\"Piste loisirs\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_28_7\">Piste loisirs<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_28_6\" name=\"wpforms[fields][28][]\" value=\"Piste carving\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_28_6\">Piste carving<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_28_5\" name=\"wpforms[fields][28][]\" value=\"Freeride\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_28_5\">Freeride<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_28_4\" name=\"wpforms[fields][28][]\" value=\"Couloirs\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_28_4\">Couloirs<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"checkbox\" id=\"wpforms-1188-field_28_8\" name=\"wpforms[fields][28][]\" value=\"Randonn\u00e9e\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1188-field_28_8\">Randonn\u00e9e<\/label><\/li><\/ul><\/div>\t\t<div id=\"wpforms-1188-field_3-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"3\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-1188-field_3\" >votre de courbes<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-1188-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-1188-field_24-container\" class=\"wpforms-field wpforms-field-select wpforms-conditional-trigger wpforms-field-select-style-modern\" data-field-id=\"24\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_24\">Utilisation envisag\u00e9e pour votre board Dupraz <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-1188-field_24\" class=\"wpforms-field-medium wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-medium\" data-search-enabled=\"\" name=\"wpforms[fields][24]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled ><\/option><option value=\"\u00c7a sera mon unique board\"  selected='selected'>\u00c7a sera mon unique board<\/option><option value=\"Cette board sera en compl\u00e9ment d&#039;une autre\" >Cette board sera en compl\u00e9ment d&#039;une autre<\/option><\/select><\/div><div id=\"wpforms-1188-field_2-container\" class=\"wpforms-field wpforms-field-textarea wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"2\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_2\">Message<\/label><textarea id=\"wpforms-1188-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" placeholder=\"Merci de nous dire quelle est cette autre board, sa taille et son utilisation. Par ailleurs, si vous avez d&#039;autres pr\u00e9cisions sur vous, votre style, vos envies, votre exp\u00e9rience, c&#039;est ici !\" ><\/textarea><\/div><div id=\"wpforms-1188-field_21-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"21\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_21\">Vous h\u00e9sitez entre ce mod\u00e8le l\u00e0 : <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-1188-field_21\" class=\"wpforms-field-small wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-small\" data-search-enabled=\"1\" name=\"wpforms[fields][21]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled ><\/option><option value=\"...\"  selected='selected'>...<\/option><option value=\"D1 5\u20192&quot; N\" >D1 5\u20192&quot; N<\/option><option value=\"D1 5\u20192&quot;\" >D1 5\u20192&quot;<\/option><option value=\"D1 5&#039;5&quot; STD\" >D1 5&#039;5&quot; STD<\/option><option value=\"D1 5&#039;5&quot; +\" >D1 5&#039;5&quot; +<\/option><option value=\"D1 5&#039;5&quot; ++\" >D1 5&#039;5&quot; ++<\/option><option value=\"D1 6&#039; +\" >D1 6&#039; +<\/option><option value=\"D1 6&#039; ++\" >D1 6&#039; ++<\/option><option value=\"D1 6&#039;3&quot;\" >D1 6&#039;3&quot;<\/option><option value=\"Choice 12\" >Choice 12<\/option><option value=\"X5-CARBON\" >X5-CARBON<\/option><option value=\"X6-CARBON\" >X6-CARBON<\/option><option value=\"Choice 15\" >Choice 15<\/option><option value=\"D-TOUR X5\" >D-TOUR X5<\/option><option value=\"D-TOUR X6\" >D-TOUR X6<\/option><\/select><\/div><div id=\"wpforms-1188-field_22-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"22\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_22\">et ce mod\u00e8le ci : <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-1188-field_22\" class=\"wpforms-field-small wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-small\" data-search-enabled=\"1\" name=\"wpforms[fields][22]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled ><\/option><option value=\"...\"  selected='selected'>...<\/option><option value=\"D1 5\u20192&quot; N\" >D1 5\u20192&quot; N<\/option><option value=\"D1 5\u20192&quot;\" >D1 5\u20192&quot;<\/option><option value=\"D1 5&#039;5&quot; STD\" >D1 5&#039;5&quot; STD<\/option><option value=\"D1 5&#039;5&quot; +\" >D1 5&#039;5&quot; +<\/option><option value=\"D1 5&#039;5&quot; ++\" >D1 5&#039;5&quot; ++<\/option><option value=\"D1 6&#039; +\" >D1 6&#039; +<\/option><option value=\"D1 6&#039; ++\" >D1 6&#039; ++<\/option><option value=\"D1 6&#039;3&quot;\" >D1 6&#039;3&quot;<\/option><option value=\"Choice 12\" >Choice 12<\/option><option value=\"X5-CARBON\" >X5-CARBON<\/option><option value=\"X6-CARBON\" >X6-CARBON<\/option><option value=\"Choice 15\" >Choice 15<\/option><option value=\"D-TOUR X5\" >D-TOUR X5<\/option><option value=\"D-TOUR X6\" >D-TOUR X6<\/option><\/select><\/div><div id=\"wpforms-1188-field_23-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"23\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_23\">et \u00e9ventuellement celui-ci : <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-1188-field_23\" class=\"wpforms-field-small wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-small\" data-search-enabled=\"1\" name=\"wpforms[fields][23]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled ><\/option><option value=\"...\"  selected='selected'>...<\/option><option value=\"D1 5\u20192&quot; N\" >D1 5\u20192&quot; N<\/option><option value=\"D1 5\u20192&quot;\" >D1 5\u20192&quot;<\/option><option value=\"D1 5&#039;5&quot; STD\" >D1 5&#039;5&quot; STD<\/option><option value=\"D1 5&#039;5&quot; +\" >D1 5&#039;5&quot; +<\/option><option value=\"D1 5&#039;5&quot; ++\" >D1 5&#039;5&quot; ++<\/option><option value=\"D1 6&#039; +\" >D1 6&#039; +<\/option><option value=\"D1 6&#039; ++\" >D1 6&#039; ++<\/option><option value=\"D1 6&#039;3&quot;\" >D1 6&#039;3&quot;<\/option><option value=\"Choice 12\" >Choice 12<\/option><option value=\"X5-CARBON\" >X5-CARBON<\/option><option value=\"X6-CARBON\" >X6-CARBON<\/option><option value=\"Choice 15\" >Choice 15<\/option><option value=\"D-TOUR X5\" >D-TOUR X5<\/option><option value=\"D-TOUR X6\" >D-TOUR X6<\/option><\/select><\/div><div id=\"wpforms-1188-field_25-container\" class=\"wpforms-field wpforms-field-textarea wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"25\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-1188-field_25\">Message<\/label><textarea id=\"wpforms-1188-field_25\" class=\"wpforms-field-medium\" name=\"wpforms[fields][25]\" placeholder=\"Autres pr\u00e9cisions sur vous, votre style, vos envies, votre exp\u00e9rience, c&#039;est ici !\" ><\/textarea><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-1188-field_3-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-1188-field_3-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-1188-field_3-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"1188\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/dupraz-snow.com\/en\/wp-json\/wp\/v2\/pages\/1182\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-1188\" class=\"wpforms-submit\" data-alt-text=\"Envoi...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-css_id=\"zlzj977\" data-lazy=\"1\" class=\"module_row themify_builder_row fullwidth tb_zlzj977 tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_opft977 first\">\n                    <!-- module image -->\n<div  class=\"module module-image tb_j3oe893 image-top   auto_fullwidth tf_mw\" data-lazy=\"1\">\n        <div class=\"image-wrap tf_rel tf_mw\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1171\" src=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/Dupraz-snow-powder-slash-1.jpg\" class=\"wp-post-image wp-image-1202\" title=\"Dupraz-snow-powder-slash-1\" alt=\"Dupraz Snowboard\" srcset=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/Dupraz-snow-powder-slash-1.jpg 2000w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/Dupraz-snow-powder-slash-1-300x176.jpg 300w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/Dupraz-snow-powder-slash-1-600x351.jpg 600w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/Dupraz-snow-powder-slash-1-1024x600.jpg 1024w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/Dupraz-snow-powder-slash-1-768x450.jpg 768w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/Dupraz-snow-powder-slash-1-1536x899.jpg 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\">    \n        <\/div>\n    <!-- \/image-wrap -->\n    \n        <\/div>\n<!-- \/module image -->        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->","protected":false},"excerpt":{"rendered":"<p>Choisir sa board Vous h\u00e9sitez entre plusieurs mod\u00e8les ? Contactez nous directement. Afin de pouvoir vous renseigner de mani\u00e8re personnalis\u00e9e et vous conseiller ainsi sur le produit le plus adapt\u00e9 \u00e0 votre gabarit, exp\u00e9rience et style de ride, veuillez SVP remplir le formulaire ci-dessous. Nous vous r\u00e9pondrons aussi vite que possible. Le staff Dupraz Snow [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-1182","page","type-page","status-publish","hentry","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"builder_content":"<img src=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/DUPRAZ_D1-original-range-1.jpg\" title=\"DUPRAZ_D1-original range-1\" alt=\"\" srcset=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/DUPRAZ_D1-original-range-1.jpg 1024w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/DUPRAZ_D1-original-range-1-300x225.jpg 300w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/DUPRAZ_D1-original-range-1-600x450.jpg 600w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/DUPRAZ_D1-original-range-1-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\n<h1 align=\"left\">Choisir sa board<\/h1>\n<p>Vous h\u00e9sitez entre plusieurs mod\u00e8les ? Contactez nous directement.\u00a0<\/p> <p>Afin de pouvoir vous renseigner de mani\u00e8re personnalis\u00e9e et vous conseiller ainsi sur le produit le plus adapt\u00e9 \u00e0 votre gabarit, exp\u00e9rience et style de ride, veuillez SVP remplir le formulaire ci-dessous.<\/p>\n<p>Nous vous r\u00e9pondrons aussi vite que possible.<\/p>\n<strong>Le staff Dupraz Snow<br \/><br \/><br \/><\/strong> Avant de remplir le formulaire, vous pouvez lire les conseils ci-dessous...\n<ul><li><h4>Conseils pour choisir la bonne board<\/h4><strong>Choisir la bonne taille<\/strong> \u00a0\n<p>Notre shape a \u00e9t\u00e9 maintes fois reconnu par les tests magazines et par tous ceux qui ont essay\u00e9, comme le plus polyvalent qui soit sur le march\u00e9. Nous avons simplement d\u00e9clin\u00e9 ce concept en tailles et flex diff\u00e9rents, ce qui couvre la grande majorit\u00e9 des riders. Ce choix de diff\u00e9rentes rigidit\u00e9s de la D1 permet de se rapprocher au plus pr\u00e8s d'une conception personnalis\u00e9e, de ce qu'on pourrait appeler du \"sur-mesure\".<\/p> <p>1 - Board de votre taille : programme all mountain classique.<br \/>2 - Une taille en-dessous : programme all mountain ludique avec board plus joueuse, plus maniable.<br \/>3 - Une taille au-dessus : programme all mountain avec grosse option freeride.<\/p>\n<a href=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/choix_tailles.jpg\"><img src=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/choix_tailles.jpg\" alt=\"\" width=\"409\" height=\"373\" \/><\/a> <strong>Exemple avec un rider de 1m80 :<\/strong> - Prendra un 6' (1m78) pour un programme freeride. - Prendra une 6'3\" (193cm) pour un usage hors piste et grosse poudre. - Prendra une 5'5\" (165 cm) pour un usage plus joueur, plus polyvalent. - Prendra une 5'2\" (158 cm) pour un usage shred \/ fish. \u00a0 <strong>Exemple avec une rideuse qui mesure 1m62 :<\/strong> - Si elle prend la taille juste au-dessus d'elle, soit une 5'5\" (1m65) son programme sera\u00a0r\u00e9solument freeride. - Avec une 5'2\" (1m58) elle sera toujours \u00e0 l'aise en poudre mais va beaucoup gagner en\u00a0maniabilit\u00e9 sur piste. \u00a0\n<strong>Comparaisons avec d'autres shapes<\/strong> \u00a0Nos shapes ont cette particularit\u00e9 d'avoir une tr\u00e8s faible longueur de carre par rapport \u00e0 la longueur totale de la board. Les avantages sont une plus grande maniabilit\u00e9 alli\u00e9e \u00e0 une portance importante, qui vous permettra de flotter les jours de poudreuse. En effet notre longue spatule n'entrave en rien les capacit\u00e9s de ride sur piste, par contre en poudreuse elle offre des acc\u00e9l\u00e9rations et une flottaison meilleurs que n'importe quel autre shape du march\u00e9.\n\u00a0\n- Nos 5'2\" qui mesurent 158cm sont aussi habiles et joueuses sur piste d'une board de 152 au shape classique. En poudreuse par contre les 5'2\" laissent les boards\u00a0 de 160 cm\u00a0 loin derri\u00e8re et vous ridez sur les deux pieds, \u00e9quilibr\u00e9, sans soucis pour d\u00e9jauger et sans vous fatiguer les cuisses ! \u00a0- Sur le m\u00eame principe, nos 5'5\" qui font 165cm sont aussi maniables que des boards au shape classique de 157 cm. \u00a0- Les 6' (178cm) \u00e9quivalent \u00e0 des 164, alors que notre plus grande 6'3\" se ride comme une 172. \u00a0 Voici un petit dessin qui r\u00e9sume ces diff\u00e9rences.<br \/><a href=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/dupraz-size-chart-1.jpg\"><img src=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/dupraz-size-chart-1.jpg\" alt=\"\" width=\"520\" height=\"362\" \/><\/a> \u00a0\n<strong>Vous avez encore un doute ?<\/strong> Demandez quelle taille de board vous irait le mieux en remplissant le formulaire ci-dessous.<br \/>Nous r\u00e9pondons vite et\u00a0pr\u00e9cis\u00e9ment \u00e0 toutes vos questions.<\/li><li><h4>Choisir le bon flex<\/h4><strong>Choisir le bon flex<\/strong> \u00a0 Nos gamme est compos\u00e9e de mod\u00e8les class\u00e9s d'abord par tailles, puis sur certains mod\u00e8les par flex, afin d'\u00eatre au plus pr\u00e8s d'une board custom, parfaitement adapt\u00e9e \u00e0 votre style de ride et gabarit. \u00a0 Nos flex sont nomm\u00e9s de la fa\u00e7on suivante : \"PLAY\" (pour standard), \"FULL +\" pour un flex interm\u00e9diaire et enfin \"POWER ++\" pour un flex rigide. \u00a0 Plus la board est rigide,\u00a0 plus elle est adapt\u00e9e \u00e0 un gabarit lourd, ou alors \u00e0 quelqu'un qui ride avec des appuis puissants. A l'inverse une board souple est plus adapt\u00e9e \u00e0 quelqu'un de l\u00e9ger ou un rider (ou rideuse) qui surfe plus en toucher de neige. \u00a0 - Les mod\u00e8les 5'2\" sont en flex PLAY. - Les 5'5\" existent dans les 3 versions de flex. - La 6' en deux duret\u00e9s (+ et ++) - Les X\u00a0 sont particuli\u00e8res, car elles restent flexibles, mais avec une nervosit\u00e9 accrue. Leur flex reste cependant assez comparable \u00e0 une board de type +. - Les Split ont un flex \u00e0 peine plus r\u00e9dige d'un flex PLAY. \u00a0 - La 6'3\" est un mod\u00e8le engag\u00e9, dont le flex est assez ferme. Mais sur toute la longueur cette board se d\u00e9forme bien malgr\u00e9 tout. Son flex est un \"POWER ++\". \u00a0 <strong>Vous avez un doute ?<\/strong> Demandez nous quel flex vous irait le mieux.<\/li><\/ul>\n<h3>Ces informations vont nous permettre de choisir la meilleure board pour vous<\/h3> <h5>R\u00e9ponse personnalis\u00e9e sous 48 heures max.<\/h5>\n<p>[wpforms id=\"1188\"]<\/p>\n<img src=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/Dupraz-snow-powder-slash-1.jpg\" title=\"Dupraz-snow-powder-slash-1\" alt=\"\" srcset=\"https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/Dupraz-snow-powder-slash-1.jpg 2000w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/Dupraz-snow-powder-slash-1-300x176.jpg 300w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/Dupraz-snow-powder-slash-1-600x351.jpg 600w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/Dupraz-snow-powder-slash-1-1024x600.jpg 1024w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/Dupraz-snow-powder-slash-1-768x450.jpg 768w, https:\/\/dupraz-snow.com\/wp-content\/uploads\/2020\/10\/Dupraz-snow-powder-slash-1-1536x899.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>","_links":{"self":[{"href":"https:\/\/dupraz-snow.com\/en\/wp-json\/wp\/v2\/pages\/1182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dupraz-snow.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dupraz-snow.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dupraz-snow.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dupraz-snow.com\/en\/wp-json\/wp\/v2\/comments?post=1182"}],"version-history":[{"count":0,"href":"https:\/\/dupraz-snow.com\/en\/wp-json\/wp\/v2\/pages\/1182\/revisions"}],"wp:attachment":[{"href":"https:\/\/dupraz-snow.com\/en\/wp-json\/wp\/v2\/media?parent=1182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}